{"id":39403,"date":"2025-04-07T11:38:13","date_gmt":"2025-04-07T09:38:13","guid":{"rendered":"https:\/\/agap2.com\/spain\/?p=39403"},"modified":"2025-04-07T11:42:32","modified_gmt":"2025-04-07T09:42:32","slug":"agap2talent-department-manager","status":"publish","type":"post","link":"https:\/\/agap2.com\/spain\/testimonial\/agap2talent-department-manager\/","title":{"rendered":"agap2Talent : Jordi Fernandez, Department Manager"},"content":{"rendered":"<p>Crecer es importante, pero ayudar a otros a crecer lo es a\u00fan m\u00e1s.<\/p>\n<p><span style=\"color: #ffcd00\"><strong>Formar, acompa\u00f1ar y empoderar.<\/strong> <\/span>Estas tres palabras resumen a la perfecci\u00f3n el enfoque de Jordi, Department Manager en agap2, que hoy nos comparte su experiencia como coach de nuevos talentos y su visi\u00f3n del desarrollo profesional dentro de agap2.<\/p>\n<h3>Jordi, \u00bfpuedes contarnos sobre tu trayectoria profesional y tu formaci\u00f3n antes de unirte a agap2?<\/h3>\n<p><em>\u00abMi trayectoria profesional se ha desarrollado principalmente en el \u00e1mbito de la gesti\u00f3n de equipos en el sector TI, acumulando casi 4 a\u00f1os de experiencia en la gesti\u00f3n de proyectos, equipos y clientes.\u00bb<\/em><\/p>\n<p>Antes de unirse a agap2, Jordi se form\u00f3 en Econom\u00eda, con especialidad en gesti\u00f3n de empresas, en la Universidad de las Islas Baleares. <em>\u00abDurante la carrera adquir\u00ed competencias clave en negociaci\u00f3n, gesti\u00f3n del tiempo, organizaci\u00f3n y toma de decisiones, habilidades fundamentales para el rol de Business Manager.\u00bb<\/em><\/p>\n<p><em>\u00abGracias a mi incorporaci\u00f3n a agap2, pude aplicar directamente estos conocimientos en un entorno comercial, adapt\u00e1ndolos al desarrollo de negocio y a la gesti\u00f3n de clientes.\u00bb<\/em><\/p>\n<h3>En agap2, el coaching es indispensable. \u00bfC\u00f3mo te ha ayudado este acompa\u00f1amiento en tu camino como Business Manager?<\/h3>\n<p><em>\u00abEl coaching ha sido fundamental para ganar confianza desde el principio.\u00bb<\/em><\/p>\n<p>Contar con el apoyo constante de su coach le permiti\u00f3 tomar r\u00e1pidamente las riendas de su cartera de clientes y dominar las reuniones comerciales. Jordi destaca el valor de sentirse acompa\u00f1ado desde el inicio: <em>\u00abMi coach siempre estuvo disponible para resolver dudas y compartir experiencias. Eso facilit\u00f3 much\u00edsimo mi adaptaci\u00f3n y crecimiento.\u00bb<\/em><\/p>\n<h3>El programa de formaci\u00f3n de agap2 est\u00e1 dise\u00f1ado para acelerar la integraci\u00f3n. \u00bfC\u00f3mo acompa\u00f1as t\u00fa a tu Junior?<\/h3>\n<p>Desde el primer d\u00eda, Jordi se asegura de que su Junior comprenda bien el rol de Business Manager y el funcionamiento de la organizaci\u00f3n. Su enfoque combina cercan\u00eda con autonom\u00eda:<\/p>\n<p><em>\u00abTrabajamos juntos en la preparaci\u00f3n de sus primeras reuniones con clientes y candidatos, y en la gesti\u00f3n de proyectos. Me gusta asegurar un acompa\u00f1amiento pr\u00f3ximo, pero tambi\u00e9n darle el espacio necesario para que desarrolle sus propias competencias.\u00bb<\/em><\/p>\n<h3>El rol de coach implica guiar sin quitar autonom\u00eda. \u00bfC\u00f3mo encuentras ese equilibrio?<\/h3>\n<p><em>\u201cDurante las primeras semanas, acompa\u00f1o a mi Junior en diversas reuniones, compartiendo consejos, buenas pr\u00e1cticas y algunos de mis mejores tips. Es importante encontrar el equilibrio entre guiar y dejar espacio para que el Junior aprenda por s\u00ed mismo.<\/em><\/p>\n<p><em>Le animo a que tome iniciativas desde el inicio, asegur\u00e1ndome de que siempre sepa que puede contar conmigo para resolver dudas o analizar situaciones. Esto permite que gane confianza mientras desarrolla su criterio propio.\u201d<\/em><\/p>\n<h3>\u00bfQu\u00e9 te aporta personalmente ser coach como Department Manager?<\/h3>\n<p><em>\u00abEs importante crecer y conseguir tus propios objetivos, pero es mejor a\u00fan ayudar a que otros lo consigan.\u00bb<\/em><\/p>\n<p>Para Jordi, ser coach es una experiencia muy enriquecedora. Le permite compartir lo que ha aprendido a lo largo de su trayectoria, pero tambi\u00e9n le obliga a reflexionar sobre sus propias pr\u00e1cticas. <em>\u00abVer c\u00f3mo mi Junior evoluciona, gana en confianza y adquiere autonom\u00eda es realmente gratificante. Y al final, su desarrollo tambi\u00e9n contribuye al m\u00edo.\u00bb<\/em><\/p>\n<p>\ud83d\udce9 \u00bfQuieres unirte al equipo y contribuir al futuro de agap2? \u00a1Env\u00edanos tu candidatura a <a href=\"mailto:talent@agap2.es\">talent@agap2.es<\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Crecer es importante, pero ayudar a otros a crecer lo es a\u00fan m\u00e1s. Formar, acompa\u00f1ar y empoderar. Estas tres palabras resumen a la perfecci\u00f3n el enfoque de Jordi, Department Manager en agap2, que hoy nos comparte su experiencia como coach&#8230;<\/p>\n","protected":false},"author":11,"featured_media":39519,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"footnotes":""},"categories":[40],"tags":[],"country":[79],"class_list":["post-39403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-testimonial","country-spain"],"acf":[],"lang":"es","translations":{"es":39403},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/agap2.com\/spain\/wp-json\/wp\/v2\/posts\/39403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agap2.com\/spain\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agap2.com\/spain\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agap2.com\/spain\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/agap2.com\/spain\/wp-json\/wp\/v2\/comments?post=39403"}],"version-history":[{"count":8,"href":"https:\/\/agap2.com\/spain\/wp-json\/wp\/v2\/posts\/39403\/revisions"}],"predecessor-version":[{"id":39521,"href":"https:\/\/agap2.com\/spain\/wp-json\/wp\/v2\/posts\/39403\/revisions\/39521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agap2.com\/spain\/wp-json\/wp\/v2\/media\/39519"}],"wp:attachment":[{"href":"https:\/\/agap2.com\/spain\/wp-json\/wp\/v2\/media?parent=39403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agap2.com\/spain\/wp-json\/wp\/v2\/categories?post=39403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agap2.com\/spain\/wp-json\/wp\/v2\/tags?post=39403"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/agap2.com\/spain\/wp-json\/wp\/v2\/country?post=39403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}